{"id":24637,"date":"2026-05-02T21:22:38","date_gmt":"2026-05-02T21:22:38","guid":{"rendered":"https:\/\/dentalclean.com\/br\/?post_type=produto&#038;p=24637"},"modified":"2026-05-02T21:22:39","modified_gmt":"2026-05-02T21:22:39","slug":"escova-l2-adulto-mandalorian","status":"publish","type":"produto","link":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/","title":{"rendered":"Escova L2 Adulto Mandalorian"},"content":{"rendered":"","protected":false},"parent":0,"template":"","meta":{"_acf_changed":true},"categories":[104],"tags":[56,16,18,83,9],"categoria":[89,60],"categoria-de-teste":[],"class_list":["post-24637","produto","type-produto","status-publish","hentry","category-dentalclean-star-wars","tag-banner-promocional-02","tag-banner-promocional","tag-beneficios-extras","tag-destaque-pro-2","tag-9","categoria-categoria-de-produtos","categoria-dentalclean-star-wars"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escova L2 Adulto Mandalorian - Dentalclean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escova L2 Adulto Mandalorian - Dentalclean\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/\" \/>\n<meta property=\"og:site_name\" content=\"Dentalclean\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T21:22:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/\",\"url\":\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/\",\"name\":\"Escova L2 Adulto Mandalorian - Dentalclean\",\"isPartOf\":{\"@id\":\"https:\/\/dentalclean.com\/br\/#website\"},\"datePublished\":\"2026-05-02T21:22:38+00:00\",\"dateModified\":\"2026-05-02T21:22:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dentalclean.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escova L2 Adulto Mandalorian\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dentalclean.com\/br\/#website\",\"url\":\"https:\/\/dentalclean.com\/br\/\",\"name\":\"Dentalclean\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dentalclean.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dentalclean.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dentalclean.com\/br\/#organization\",\"name\":\"Dentalclean\",\"url\":\"https:\/\/dentalclean.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/dentalclean.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dentalclean.com\/br\/wp-content\/uploads\/2024\/07\/logo.png\",\"contentUrl\":\"https:\/\/dentalclean.com\/br\/wp-content\/uploads\/2024\/07\/logo.png\",\"width\":700,\"height\":134,\"caption\":\"Dentalclean\"},\"image\":{\"@id\":\"https:\/\/dentalclean.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escova L2 Adulto Mandalorian - Dentalclean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/","og_locale":"pt_BR","og_type":"article","og_title":"Escova L2 Adulto Mandalorian - Dentalclean","og_url":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/","og_site_name":"Dentalclean","article_modified_time":"2026-05-02T21:22:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/","url":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/","name":"Escova L2 Adulto Mandalorian - Dentalclean","isPartOf":{"@id":"https:\/\/dentalclean.com\/br\/#website"},"datePublished":"2026-05-02T21:22:38+00:00","dateModified":"2026-05-02T21:22:39+00:00","breadcrumb":{"@id":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dentalclean.com\/br\/escova-l2-adulto-mandalorian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dentalclean.com\/br\/"},{"@type":"ListItem","position":2,"name":"Escova L2 Adulto Mandalorian"}]},{"@type":"WebSite","@id":"https:\/\/dentalclean.com\/br\/#website","url":"https:\/\/dentalclean.com\/br\/","name":"Dentalclean","description":"","publisher":{"@id":"https:\/\/dentalclean.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dentalclean.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/dentalclean.com\/br\/#organization","name":"Dentalclean","url":"https:\/\/dentalclean.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dentalclean.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/dentalclean.com\/br\/wp-content\/uploads\/2024\/07\/logo.png","contentUrl":"https:\/\/dentalclean.com\/br\/wp-content\/uploads\/2024\/07\/logo.png","width":700,"height":134,"caption":"Dentalclean"},"image":{"@id":"https:\/\/dentalclean.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/produto\/24637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/produto"}],"about":[{"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/types\/produto"}],"wp:attachment":[{"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/media?parent=24637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/categories?post=24637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/tags?post=24637"},{"taxonomy":"categoria","embeddable":true,"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/categoria?post=24637"},{"taxonomy":"categoria-de-teste","embeddable":true,"href":"https:\/\/dentalclean.com\/br\/wp-json\/wp\/v2\/categoria-de-teste?post=24637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}